{"id":344,"count":5,"description":"","link":"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/","name":"Uncategorized","slug":"uncategorized-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized archivos - Patio del Posadero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized archivos - Patio del Posadero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Patio del Posadero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/en\\\/category\\\/uncategorized-en\\\/\",\"url\":\"https:\\\/\\\/patiodelposadero.com\\\/en\\\/category\\\/uncategorized-en\\\/\",\"name\":\"Uncategorized archivos - Patio del Posadero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/en\\\/category\\\/uncategorized-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/en\\\/category\\\/uncategorized-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/patiodelposadero.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/#website\",\"url\":\"https:\\\/\\\/patiodelposadero.com\\\/\",\"name\":\"Patio del Posadero\",\"description\":\"1\u00ba Hotel Boutique de C\u00f3rdoba recomendado\",\"publisher\":{\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/#organization\"},\"alternateName\":\"Hotel Boutique Patio del Posadero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patiodelposadero.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/#organization\",\"name\":\"Patio del Posadero\",\"url\":\"https:\\\/\\\/patiodelposadero.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patiodelposadero.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_2021_patio_del_posadero_color_trim-1.png\",\"contentUrl\":\"https:\\\/\\\/patiodelposadero.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_2021_patio_del_posadero_color_trim-1.png\",\"width\":2015,\"height\":1410,\"caption\":\"Patio del Posadero\"},\"image\":{\"@id\":\"https:\\\/\\\/patiodelposadero.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized archivos - Patio del Posadero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized archivos - Patio del Posadero","og_url":"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/","og_site_name":"Patio del Posadero","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/","url":"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/","name":"Uncategorized archivos - Patio del Posadero","isPartOf":{"@id":"https:\/\/patiodelposadero.com\/#website"},"breadcrumb":{"@id":"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/patiodelposadero.com\/en\/category\/uncategorized-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/patiodelposadero.com\/en\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/patiodelposadero.com\/#website","url":"https:\/\/patiodelposadero.com\/","name":"Patio del Posadero","description":"1\u00ba Hotel Boutique de C\u00f3rdoba recomendado","publisher":{"@id":"https:\/\/patiodelposadero.com\/#organization"},"alternateName":"Hotel Boutique Patio del Posadero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patiodelposadero.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/patiodelposadero.com\/#organization","name":"Patio del Posadero","url":"https:\/\/patiodelposadero.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/patiodelposadero.com\/#\/schema\/logo\/image\/","url":"https:\/\/patiodelposadero.com\/wp-content\/uploads\/2025\/01\/logo_2021_patio_del_posadero_color_trim-1.png","contentUrl":"https:\/\/patiodelposadero.com\/wp-content\/uploads\/2025\/01\/logo_2021_patio_del_posadero_color_trim-1.png","width":2015,"height":1410,"caption":"Patio del Posadero"},"image":{"@id":"https:\/\/patiodelposadero.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/patiodelposadero.com\/en\/wp-json\/wp\/v2\/categories\/344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patiodelposadero.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/patiodelposadero.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/patiodelposadero.com\/en\/wp-json\/wp\/v2\/posts?categories=344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}